{"id":2,"count":11,"description":"","link":"https:\/\/atlanticgoaltendingacademy.com\/fr\/category\/programs\/","name":"PROGRAMS","slug":"programs","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROGRAMS Archives - atlanticgoaltendingacademy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlanticgoaltendingacademy.com\/category\/programs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROGRAMS Archives - atlanticgoaltendingacademy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlanticgoaltendingacademy.com\/category\/programs\/\" \/>\n<meta property=\"og:site_name\" content=\"atlanticgoaltendingacademy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/fr\\\/category\\\/programs\\\/\",\"url\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/fr\\\/category\\\/programs\\\/\",\"name\":\"PROGRAMS Archives - atlanticgoaltendingacademy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/fr\\\/category\\\/programs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"description\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/category\\\/programs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#website\",\"url\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/\",\"name\":\"Atlantic Goaltending Academy\",\"description\":\"Atlantic Canada&#039;s Largest Goaltending Academy\",\"publisher\":{\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#organization\",\"name\":\"Atlantic Goaltending Academy\",\"url\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/AHGGoaltendingAcademyLogo_pos-white-g.png\",\"contentUrl\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/AHGGoaltendingAcademyLogo_pos-white-g.png\",\"width\":1665,\"height\":726,\"caption\":\"Atlantic Goaltending Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/atlanticgoaltendingacademy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AGAGOALTENDING\\\/?ref=bookmarks\",\"https:\\\/\\\/www.instagram.com\\\/atlanticgoaltendingacademy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGRAMS Archives - atlanticgoaltendingacademy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlanticgoaltendingacademy.com\/category\/programs\/","og_locale":"fr_FR","og_type":"article","og_title":"PROGRAMS Archives - atlanticgoaltendingacademy","og_url":"https:\/\/atlanticgoaltendingacademy.com\/category\/programs\/","og_site_name":"atlanticgoaltendingacademy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/atlanticgoaltendingacademy.com\/fr\/category\/programs\/","url":"https:\/\/atlanticgoaltendingacademy.com\/fr\/category\/programs\/","name":"PROGRAMS Archives - atlanticgoaltendingacademy","isPartOf":{"@id":"https:\/\/atlanticgoaltendingacademy.com\/#website"},"breadcrumb":{"@id":"https:\/\/atlanticgoaltendingacademy.com\/fr\/category\/programs\/#breadcrumb"},"inLanguage":"fr-FR","description":""},{"@type":"BreadcrumbList","@id":"https:\/\/atlanticgoaltendingacademy.com\/category\/programs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/atlanticgoaltendingacademy.com\/"},{"@type":"ListItem","position":2,"name":"PROGRAMS"}]},{"@type":"WebSite","@id":"https:\/\/atlanticgoaltendingacademy.com\/#website","url":"https:\/\/atlanticgoaltendingacademy.com\/","name":"Atlantic Goaltending Academy","description":"Atlantic Canada&#039;s Largest Goaltending Academy","publisher":{"@id":"https:\/\/atlanticgoaltendingacademy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlanticgoaltendingacademy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/atlanticgoaltendingacademy.com\/#organization","name":"Atlantic Goaltending Academy","url":"https:\/\/atlanticgoaltendingacademy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/atlanticgoaltendingacademy.com\/#\/schema\/logo\/image\/","url":"https:\/\/atlanticgoaltendingacademy.com\/wp-content\/uploads\/2019\/02\/AHGGoaltendingAcademyLogo_pos-white-g.png","contentUrl":"https:\/\/atlanticgoaltendingacademy.com\/wp-content\/uploads\/2019\/02\/AHGGoaltendingAcademyLogo_pos-white-g.png","width":1665,"height":726,"caption":"Atlantic Goaltending Academy"},"image":{"@id":"https:\/\/atlanticgoaltendingacademy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AGAGOALTENDING\/?ref=bookmarks","https:\/\/www.instagram.com\/atlanticgoaltendingacademy\/"]}]}},"_links":{"self":[{"href":"https:\/\/atlanticgoaltendingacademy.com\/fr\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlanticgoaltendingacademy.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/atlanticgoaltendingacademy.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/atlanticgoaltendingacademy.com\/fr\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}